{"id":42879,"date":"2022-06-15T20:39:03","date_gmt":"2022-06-15T20:39:03","guid":{"rendered":"https:\/\/botoxcapilar.org\/?page_id=42879"},"modified":"2022-06-15T21:02:57","modified_gmt":"2022-06-15T21:02:57","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/botoxcapilar.org\/en\/privacy-policy","title":{"rendered":"Privacy"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La Pol\u00edtica de Privacidad de<\/span><a href=\"http:\/\/www.botoxcapilar.org\/\"> <span style=\"font-weight: 400;\">www.botoxcapilar.org<\/span><\/a><span style=\"font-weight: 400;\"> es aplicable a todos los Usuarios del sitio web y de sus servicios desde el momento de la aceptaci\u00f3n de los <\/span><span style=\"font-weight: 400;\">T\u00e9rminos y Condiciones de Uso<\/span><span style=\"font-weight: 400;\">, y tiene como objetivo que los Usuarios conozcan el trato que BOTOX CAPILAR, con domicilio en calle Mendoza 2936, piso 3, Ciudad Aut\u00f3noma de Buenos Aires, Argentina (en adelante, BOTOX CAPILAR) les dar\u00e1 a sus datos personales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol>\n<li><b> Disposiciones Generales. <\/b><span style=\"font-weight: 400;\">La informaci\u00f3n personal de los Usuarios es de extrema importancia para BOTOX CAPILAR. Es por ello que utilizamos todos los medios administrativos y t\u00e9cnicos a nuestro alcance, as\u00ed como todos los resguardos legales necesarios para asegurar la protecci\u00f3n de los datos personales y la privacidad.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">La presente Pol\u00edtica de Privacidad se aplica a toda informaci\u00f3n personal de los Usuarios obtenidas como consecuencia de la utilizaci\u00f3n del sitio web y de la contrataci\u00f3n de los servicios ofrecidos en el mismo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"2\">\n<li><b> Formas de obtenci\u00f3n de datos.<\/b><span style=\"font-weight: 400;\"> BOTOX CAPILAR recoger\u00e1 datos personales de los Usuarios a trav\u00e9s de formularios e interacciones dentro del sitio web, de los contratos comerciales que realice y de las comunicaciones electr\u00f3nicas que realice con los Usuarios. No ser\u00e1 necesario facilitar ning\u00fan dato de car\u00e1cter personal para la navegaci\u00f3n por el sitio web.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"3\">\n<li><b> Finalidad.<\/b><span style=\"font-weight: 400;\"> En cumplimiento de lo establecido en los arts. 2, 7 y 8 de la Ley 25.326, BOTOX CAPILAR no solicitar\u00e1 informaci\u00f3n que sea incompatible con la finalidad del sitio web o de sus servicios, ni que directa o indirectamente revele datos sensibles de los Usuarios, como ser datos que revelan origen racial y \u00e9tnico, opiniones pol\u00edticas, convicciones religiosas, filos\u00f3ficas o morales, afiliaci\u00f3n sindical, informaci\u00f3n referente a la salud o a la vida sexual. De la misma manera, BOTOX CAPILAR sugiere a los Usuarios no incluir esta informaci\u00f3n en sus comunicaciones o interacciones a trav\u00e9s del sitio web.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"4\">\n<li><b> Datos recolectados.<\/b><span style=\"font-weight: 400;\"> Los datos personales que BOTOX CAPILAR recolecta a trav\u00e9s del sitio web son nombre, apellido, e-mail y datos que pudieran ser obtenidos en el asunto y en el cuerpo del mensaje.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">En el Formulario de Comentarios se solicitan el nombre, el correo electr\u00f3nico, el sitio web y el comentario. Cuando el USUARIO deja un comentario, BOTOX CAPILAR recopila los datos que se muestran en el formulario, como ser la direcci\u00f3n IP y la cadena de agentes de usuario del navegador para ayudar a la detecci\u00f3n de SPAM.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una cadena an\u00f3nima creada a partir de tu direcci\u00f3n de correo electr\u00f3nico (tambi\u00e9n llamada hash) puede ser proporcionada al servicio de Gravatar para ver si se est\u00e1 usando. La Pol\u00edtica de Privacidad del servicio Gravatar est\u00e1 disponible aqu\u00ed:<\/span><a href=\"https:\/\/automattic.com\/privacy\/\"> <span style=\"font-weight: 400;\">https:\/\/automattic.com\/privacy\/<\/span><\/a><span style=\"font-weight: 400;\">. Despu\u00e9s de la aprobaci\u00f3n del comentario por parte de BOTOX CAPILAR, la imagen del perfil ser\u00e1 visible para el p\u00fablico en el contexto de dicho comentario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En el Formulario de Contacto se solicitar\u00e1 el nombre, correo electr\u00f3nico, asunto y mensaje. La informaci\u00f3n que se recoja a partir de los contactos a trav\u00e9s de este formulario no ser\u00e1 utilizada con fines comerciales o de marketing.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La informaci\u00f3n que recolecta el sitio web a trav\u00e9s de Analytics ser\u00e1 utilizada para medir y mejorar la experiencia del USUARIO, para medir su inter\u00e9s en los contenidos y mejorar la calidad de \u00e9stos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La informaci\u00f3n que recolecta el sitio web a trav\u00e9s de las cookies de AdSense, ser\u00e1 utilizada por AdSense para mostrar publicidades relevantes a cada usuario.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"5\">\n<li><b> Confidencialidad.<\/b><span style=\"font-weight: 400;\"> La informaci\u00f3n personal es totalmente confidencial y BOTOX CAPILAR tomar\u00e1 las medidas de seguridad para evitar su uso desautorizado de conformidad con lo dispuesto en la Ley 25.326 de Protecci\u00f3n de Datos Personales de Argentina, y en concordancia con los est\u00e1ndares normativos de privacidad de la Uni\u00f3n Europea (en especial el Reglamento General de Protecci\u00f3n de Datos &#8211; RGPD) y Latinoam\u00e9rica.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Las comunicaciones privadas que pudieran darse entre el personal de BOTOX CAPILAR y los Usuarios o visitantes tambi\u00e9n ser\u00e1n consideradas como confidenciales. El acceso a toda esta informaci\u00f3n estar\u00e1 restringido mediante herramientas tecnol\u00f3gicas y estrictos controles internos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin embargo, no se considerar\u00e1n confidenciales las comunicaciones electr\u00f3nicas entre los Usuarios y BOTOX CAPILAR con sugerencias o consultas y\/o en cumplimiento de condiciones de promociones, concursos o publicidad.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"6\">\n<li><b> Administraci\u00f3n de la informaci\u00f3n.<\/b><span style=\"font-weight: 400;\"> Los datos obtenidos son incorporados a una base de datos titularidad de BOTOX CAPILAR, responsable tanto de su gesti\u00f3n como de su tratamiento. BOTOX CAPILAR utilizar\u00e1 la informaci\u00f3n para los siguientes fines: a) identificaci\u00f3n y autenticaci\u00f3n, b) administraci\u00f3n y gesti\u00f3n, c) mejora del servicio, d) fines estad\u00edsticos, e) env\u00edo de material, notificaciones, promociones o publicidad y actividades similares. Los datos personales no ser\u00e1n difundidos ni empleados para un fin distinto o incompatible al tenido en cuenta al ser ingresados en la base de datos.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Si se tratase de una comunicaci\u00f3n de publicidad directa no requerida o consentida previamente por el Usuario, BOTOX CAPILAR le otorgar\u00e1 la posibilidad de ser retirado o bloqueado de dicha base de datos espec\u00edfica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En caso de cesi\u00f3n o utilizaci\u00f3n para un fin diferente, BOTOX CAPILAR solicitar\u00e1 a los Usuarios su consentimiento libre, expreso e informado. En el caso de venta, cesi\u00f3n, fusi\u00f3n, consolidaci\u00f3n, venta de la totalidad o parte sustancial de sus activos, BOTOX CAPILAR podr\u00e1 revelar o transmitir dicha informaci\u00f3n a terceros.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"7\">\n<li><b> Registro de la Base de Datos.<\/b><span style=\"font-weight: 400;\"> Los datos recabados por el sitio web son incorporados a una base de datos de la cual BOTOX CAPILAR es responsable. La misma se encuentra registrada en el Registro Nacional de Bases de Datos Privadas de la Agencia de Acceso a la Informaci\u00f3n P\u00fablica (AAIP) de la Rep\u00fablica Argentina bajo el n\u00famero de registro <\/span><span style=\"font-weight: 400;\">N\u00b0 34975<\/span><span style=\"font-weight: 400;\">, en cumplimiento de lo dispuesto en el art. 3 de la Ley 25.326 de Protecci\u00f3n de Datos Personales.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">La Agencia de Acceso a la Informaci\u00f3n P\u00fablica, \u00d3rgano de Control de la Ley N\u00ba 25.326, tiene la atribuci\u00f3n de atender las denuncias y reclamos que se interpongan con relaci\u00f3n al incumplimiento de las normas sobre protecci\u00f3n de datos personales. El sitio web para consultas sobre responsables inscriptos es https:\/\/www.argentina.gob.ar\/aaip\/datospersonales<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"8\">\n<li><b> Derechos.<\/b><span style=\"font-weight: 400;\"> El Usuario tiene la facultad de ejercer el derecho de acceso a sus datos en forma gratuita a intervalos no inferiores a 6 meses, salvo que se acredite un inter\u00e9s leg\u00edtimo al efecto conforme lo establecido en el art\u00edculo 14, inciso 3 de la Ley N\u00ba 25.326. La Agencia de Acceso a la Informaci\u00f3n P\u00fablica (AAIP), \u00d3rgano de Control de la Ley N\u00ba 25.326, tiene la atribuci\u00f3n de atender las denuncias y reclamos que se interpongan con relaci\u00f3n al incumplimiento de las normas sobre protecci\u00f3n de datos personales.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Asimismo, se deja constancia que el titular de los datos podr\u00e1 en cualquier momento solicitar el retiro o bloqueo de su nombre de los bancos de datos (Ley 25.326, art. 27, inc. 3). Esto se hace en cumplimiento de lo establecido en el Decreto 1558\/2001, art. 27, p\u00e1rrafo 3, que establece que \u201cen toda comunicaci\u00f3n con fines de publicidad que se realice por correo, tel\u00e9fono, correo electr\u00f3nico, Internet u otro medio a distancia a conocer, se deber\u00e1 indicar, en forma expresa y destacada, la posibilidad del titular del dato de solicitar el retiro o bloqueo, total o parcial, de su nombre de la base de datos. A pedido del interesado, se deber\u00e1 informar el nombre del responsable o usuario del banco de datos que provey\u00f3 la informaci\u00f3n\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"9\">\n<li><b> Procedimiento.<\/b><span style=\"font-weight: 400;\"> Para que el Usuario pueda hacer efectivo su derecho de acceso, rectificaci\u00f3n, actualizaci\u00f3n, supresi\u00f3n y confidencialidad de datos, deber\u00e1 tener en consideraci\u00f3n lo siguiente:<\/span><\/li>\n<li><b> \u00a0 <\/b> <span style=\"font-weight: 400;\">La solicitud de obtenci\u00f3n de informaci\u00f3n, rectificaci\u00f3n, actualizaci\u00f3n o supresi\u00f3n de datos personales debe efectuarse por carta documento dirigida a BOTOX CAPILAR, con domicilio en calle <\/span><span style=\"font-weight: 400;\">_______________________<\/span><span style=\"font-weight: 400;\">, acreditando la identidad y el leg\u00edtimo derecho.<\/span><\/li>\n<li><b> <\/b> <span style=\"font-weight: 400;\">Una vez recibida y aprobada dicha solicitud por BOTOX CAPILAR, se contestar\u00e1 en lenguaje accesible y entendible, previa confirmaci\u00f3n de identidad, dentro de los diez (10) d\u00edas corridos para el caso de pedido de informaci\u00f3n mientras que, para el pedido de rectificaci\u00f3n, actualizaci\u00f3n o supresi\u00f3n de datos, lo haremos en cinco (5) d\u00edas h\u00e1biles.<\/span><\/li>\n<li><b> \u00a0 <\/b> <span style=\"font-weight: 400;\">BOTOX CAPILAR contestar\u00e1 de forma clara y de acuerdo a la preferencia que haya manifestado el interesado en su solicitud. En ning\u00fan caso el informe podr\u00e1 revelar datos pertenecientes a terceros.<\/span><\/li>\n<li><b> <\/b> <span style=\"font-weight: 400;\">BOTOX CAPILAR podr\u00e1 denegar la informaci\u00f3n cuando de tal modo se pudieran obstaculizar actuaciones judiciales o administrativas en curso.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"10\">\n<li><b> Seguridad de la informaci\u00f3n.<\/b><span style=\"font-weight: 400;\"> BOTOX CAPILAR se ocupa de mantener todo el tiempo la seguridad de la informaci\u00f3n personal que brindan los Usuarios, implementando las medidas t\u00e9cnicas y organizativas internas necesarias para garantizar la seguridad y confidencialidad de los datos y tratando por todos los medios de evitar el acceso no autorizado a los mismos, en cumplimiento del art. 9 de la Ley 25.326 de Protecci\u00f3n de Datos Personales y de la Resoluci\u00f3n 47\/2018 de la Agencia de Acceso a la Informaci\u00f3n P\u00fablica (AAIP) relativa a las \u201cMedidas de Seguridad recomendadas para el Tratamiento y Conservaci\u00f3n de los Datos Personales en Medios Informatizados\u201d. Sin embargo, en raz\u00f3n del estado actual de la tecnolog\u00eda, BOTOX CAPILAR no puede garantizar que el acceso no autorizado no ocurrir\u00e1 nunca.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"11\">\n<li><b> Uso de cookies.<\/b><span style=\"font-weight: 400;\"> Los Usuarios conocen y aceptan que BOTOX CAPILAR pueda utilizar un sistema de seguimiento mediante el uso de cookies. Las cookies son archivos que se alojan en el disco r\u00edgido, con una duraci\u00f3n limitada en el tiempo que ayudan a personalizar los servicios. Las mismas facilitan el uso y navegaci\u00f3n en nuestra p\u00e1gina web, siendo en algunos casos esenciales para su funcionamiento. Las cookies permiten a la vez recoger datos a efectos de la autenticaci\u00f3n de Usuarios, validaci\u00f3n de identidad y evaluar el comportamiento y la demograf\u00eda de los Usuarios con el fin de ofrecerles un mejor servicio.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Asimismo, podr\u00e1n utilizarse con fines estad\u00edsticos tales como: fecha de la primera visita, n\u00famero de veces que se ha visitado, fecha de la \u00faltima visita, URL y dominio de la que proviene, explorador utilizado, resoluci\u00f3n de la pantalla, entre otras acciones del Usuario. Tambi\u00e9n son utilizadas las cookies para promover y hacer cumplir las reglas y seguridad del sitio. Toda esta informaci\u00f3n no ser\u00e1 asociada a los datos personales de los Usuarios. No obstante, el Usuario podr\u00e1 desactivarlas y\/o eliminarlas a trav\u00e9s de su navegador, sabiendo que, con esta opci\u00f3n, es posible que no se puedan acceder a ciertos contenidos del sitio web.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cookies de Anal\u00edtica Web: Google Analytics. Los datos que recolecta son:<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 \u00a0 Determinar el dominio que se medir\u00e1<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 \u00a0 Distinguir a los usuarios \u00fanicos<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 \u00a0 Limitar el porcentaje de solicitudes.<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 \u00a0 Recordar el n\u00famero y la duraci\u00f3n de las visitas anteriores<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 \u00a0 Recordar la informaci\u00f3n de las fuentes de tr\u00e1fico<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 \u00a0 Determinar el inicio y el fin de una sesi\u00f3n<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 \u00a0 Recordar el valor de las variables personalizadas de visitante<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cookies de Adsense. AdSense utiliza las cookies para mejorar la publicidad. Entre otros fines, suelen utilizarse para segmentarla seg\u00fan el contenido que sea relevante para los usuarios, mejorar los informes de rendimiento de las campa\u00f1as y evitar mostrar anuncios que los usuarios ya hayan visto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las cookies no contienen informaci\u00f3n personal identificable. Seg\u00fan la configuraci\u00f3n de los editores y los usuarios, la informaci\u00f3n asociada a las cookies que se utilizan en publicidad puede a\u00f1adirse a la cuenta de Google de los usuarios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Google utiliza cookies con diversos fines, entre los que se incluyen recordar tus preferencias de SafeSearch, aumentar la relevancia de los anuncios que ves, contar el n\u00famero de visitas que recibimos para acceder a una p\u00e1gina, ayudarte a registrarte en nuestros servicios, proteger tus datos o recordar tus preferencias de anuncios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<ol start=\"12\">\n<li><b> Enlaces con otros sitios web.<\/b><span style=\"font-weight: 400;\"> El sitio web puede contener enlaces o links publicitarios con sitios web de terceros. Sin embargo, BOTOX CAPILAR no dispone de control alguno ni ostenta responsabilidad alguna sobre las pol\u00edticas o medidas de protecci\u00f3n de datos de otras aplicaciones y\/o sitios web.<\/span><\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<ol start=\"13\">\n<li><b> Descargo de ganancias. <\/b><span style=\"font-weight: 400;\">BOTOX CAPILAR forma parte de varios programas de afiliados. Esto significa que muchas de las compa\u00f1\u00edas y productos que aparecen listados en este sitio web nos pagan comisiones por enviarles potenciales clientes para sus productos. Cuando el Usuario hace click en alguno de esos productos utilizando los links que aparecen en este sitio web, BOTOX CAPILAR recibe una compensaci\u00f3n por parte de la compa\u00f1\u00eda que vende el producto.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Formar parte de estos programas de afiliados y recibir esas comisiones le permite a BOTOX CAPILAR mantener actualizado el sitio web con la mejor informaci\u00f3n disponible relacionada con la salud del cabello. Todas las opiniones presentadas en el sitio web son propias o eventualmente de la persona encargada de escribir el art\u00edculo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En estos momentos trabajamos con los programas de afiliados de Amazon.com, Clickbank y Jvzoo. Actualizaremos este listado en caso de ser necesario. BOTOX CAPILAR es un participante del Programa de Afiliados de Amazon (Amazon Services LLC Associates Program), un programa publicitario de afiliados dise\u00f1ado para proporcionar a los sitios web un medio para obtener comisiones por hacer publicidad y enlazar a <\/span><a href=\"http:\/\/www.amazon.com\/\"><span style=\"font-weight: 400;\">Amazon.com<\/span><\/a><span style=\"font-weight: 400;\">\/<\/span><a href=\"http:\/\/www.amazon.es\"><span style=\"font-weight: 400;\">Amazon.es<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">La presente <\/span><span style=\"font-weight: 400;\">Pol\u00edtica de Privacidad<\/span><span style=\"font-weight: 400;\"> forma parte integrante de los <\/span><span style=\"font-weight: 400;\">T\u00e9rminos y Condiciones de Uso<\/span><span style=\"font-weight: 400;\"> de BOTOX CAPILAR.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u00daltima modificaci\u00f3n: 1 de agosto de 2018.<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Pol\u00edtica de Privacidad de www.botoxcapilar.org es aplicable a todos los Usuarios del sitio web y de sus servicios desde el momento de la aceptaci\u00f3n de los T\u00e9rminos y Condiciones de Uso, y tiene como objetivo que los Usuarios conozcan el trato que BOTOX CAPILAR, con domicilio en calle Mendoza 2936, piso 3, Ciudad Aut\u00f3noma de Buenos Aires, Argentina (en adelante, BOTOX CAPILAR) les dar\u00e1 a sus datos personales. \u00a0 Disposiciones Generales. La informaci\u00f3n personal de los Usuarios es de extrema importancia para BOTOX CAPILAR. Es por ello que utilizamos todos los medios administrativos y t\u00e9cnicos a nuestro alcance, as\u00ed <\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Privacy<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy\" \/>\n<meta property=\"og:description\" content=\"La Pol\u00edtica de Privacidad de www.botoxcapilar.org es aplicable a todos los Usuarios del sitio web y de sus servicios desde el momento de la aceptaci\u00f3n de los T\u00e9rminos y Condiciones de Uso, y tiene como objetivo que los Usuarios conozcan el trato que BOTOX CAPILAR, con domicilio en calle Mendoza 2936, piso 3, Ciudad Aut\u00f3noma de Buenos Aires, Argentina (en adelante, BOTOX CAPILAR) les dar\u00e1 a sus datos personales. \u00a0 Disposiciones Generales. La informaci\u00f3n personal de los Usuarios es de extrema importancia para BOTOX CAPILAR. Es por ello que utilizamos todos los medios administrativos y t\u00e9cnicos a nuestro alcance, as\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/botoxcapilar.org\/en\/privacy-policy\" \/>\n<meta property=\"og:site_name\" content=\"BotoxCapilar\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-15T21:02:57+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/botoxcapilar.org\/en\/privacy-policy\",\"url\":\"https:\/\/botoxcapilar.org\/en\/privacy-policy\",\"name\":\"Privacy\",\"isPartOf\":{\"@id\":\"https:\/\/botoxcapilar.org\/en\/#website\"},\"datePublished\":\"2022-06-15T20:39:03+00:00\",\"dateModified\":\"2022-06-15T21:02:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/botoxcapilar.org\/en\/privacy-policy#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/botoxcapilar.org\/en\/privacy-policy\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/botoxcapilar.org\/en\/privacy-policy#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/botoxcapilar.org\/en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/botoxcapilar.org\/en\/#website\",\"url\":\"https:\/\/botoxcapilar.org\/en\/\",\"name\":\"BotoxCapilar\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/botoxcapilar.org\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Privacy","og_description":"La Pol\u00edtica de Privacidad de www.botoxcapilar.org es aplicable a todos los Usuarios del sitio web y de sus servicios desde el momento de la aceptaci\u00f3n de los T\u00e9rminos y Condiciones de Uso, y tiene como objetivo que los Usuarios conozcan el trato que BOTOX CAPILAR, con domicilio en calle Mendoza 2936, piso 3, Ciudad Aut\u00f3noma de Buenos Aires, Argentina (en adelante, BOTOX CAPILAR) les dar\u00e1 a sus datos personales. \u00a0 Disposiciones Generales. La informaci\u00f3n personal de los Usuarios es de extrema importancia para BOTOX CAPILAR. Es por ello que utilizamos todos los medios administrativos y t\u00e9cnicos a nuestro alcance, as\u00ed","og_url":"https:\/\/botoxcapilar.org\/en\/privacy-policy","og_site_name":"BotoxCapilar","article_modified_time":"2022-06-15T21:02:57+00:00","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/botoxcapilar.org\/en\/privacy-policy","url":"https:\/\/botoxcapilar.org\/en\/privacy-policy","name":"Privacy","isPartOf":{"@id":"https:\/\/botoxcapilar.org\/en\/#website"},"datePublished":"2022-06-15T20:39:03+00:00","dateModified":"2022-06-15T21:02:57+00:00","breadcrumb":{"@id":"https:\/\/botoxcapilar.org\/en\/privacy-policy#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/botoxcapilar.org\/en\/privacy-policy"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/botoxcapilar.org\/en\/privacy-policy#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/botoxcapilar.org\/en"},{"@type":"ListItem","position":2,"name":"Privacy"}]},{"@type":"WebSite","@id":"https:\/\/botoxcapilar.org\/en\/#website","url":"https:\/\/botoxcapilar.org\/en\/","name":"BotoxCapilar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/botoxcapilar.org\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/pages\/42879"}],"collection":[{"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/comments?post=42879"}],"version-history":[{"count":3,"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/pages\/42879\/revisions"}],"predecessor-version":[{"id":42890,"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/pages\/42879\/revisions\/42890"}],"wp:attachment":[{"href":"https:\/\/botoxcapilar.org\/en\/wp-json\/wp\/v2\/media?parent=42879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}